{"id":35058,"date":"2022-06-07T16:04:35","date_gmt":"2022-06-07T14:04:35","guid":{"rendered":"https:\/\/enreach.es\/mobile\/centralita-movil\/"},"modified":"2025-07-09T16:16:02","modified_gmt":"2025-07-09T14:16:02","slug":"virtual-pbx","status":"publish","type":"page","link":"https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/","title":{"rendered":"Mobile PBX"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":27171,"parent":35052,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-35058","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mobile PBX - The PBX that works with mobiles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mobile PBX - The PBX that works with mobiles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/\" \/>\n<meta property=\"og:site_name\" content=\"Enreach ES\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T14:16:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enreach.es\/wp-content\/uploads\/2022\/06\/centralita_movil_header-e1654679073280.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/enreach.es\\\/en\\\/mobile\\\/virtual-pbx\\\/\",\"url\":\"https:\\\/\\\/enreach.es\\\/en\\\/mobile\\\/virtual-pbx\\\/\",\"name\":\"Mobile PBX - The PBX that works with mobiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enreach.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enreach.es\\\/en\\\/mobile\\\/virtual-pbx\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/enreach.es\\\/en\\\/mobile\\\/virtual-pbx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enreach.es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/centralita_movil_header-e1654679073280.png\",\"datePublished\":\"2022-06-07T14:04:35+00:00\",\"dateModified\":\"2025-07-09T14:16:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enreach.es\\\/en\\\/mobile\\\/virtual-pbx\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enreach.es\\\/en\\\/mobile\\\/virtual-pbx\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/enreach.es\\\/en\\\/mobile\\\/virtual-pbx\\\/#primaryimage\",\"url\":\"https:\\\/\\\/enreach.es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/centralita_movil_header-e1654679073280.png\",\"contentUrl\":\"https:\\\/\\\/enreach.es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/centralita_movil_header-e1654679073280.png\",\"width\":1920,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enreach.es\\\/en\\\/mobile\\\/virtual-pbx\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/enreach.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MOBILE\",\"item\":\"https:\\\/\\\/enreach.es\\\/en\\\/mobile\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mobile PBX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enreach.es\\\/#website\",\"url\":\"https:\\\/\\\/enreach.es\\\/\",\"name\":\"Enreach ES\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enreach.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mobile PBX - The PBX that works with mobiles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/","og_locale":"en_US","og_type":"article","og_title":"Mobile PBX - The PBX that works with mobiles","og_url":"https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/","og_site_name":"Enreach ES","article_modified_time":"2025-07-09T14:16:02+00:00","og_image":[{"width":1920,"height":865,"url":"https:\/\/enreach.es\/wp-content\/uploads\/2022\/06\/centralita_movil_header-e1654679073280.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/","url":"https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/","name":"Mobile PBX - The PBX that works with mobiles","isPartOf":{"@id":"https:\/\/enreach.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/#primaryimage"},"image":{"@id":"https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/#primaryimage"},"thumbnailUrl":"https:\/\/enreach.es\/wp-content\/uploads\/2022\/06\/centralita_movil_header-e1654679073280.png","datePublished":"2022-06-07T14:04:35+00:00","dateModified":"2025-07-09T14:16:02+00:00","breadcrumb":{"@id":"https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/#primaryimage","url":"https:\/\/enreach.es\/wp-content\/uploads\/2022\/06\/centralita_movil_header-e1654679073280.png","contentUrl":"https:\/\/enreach.es\/wp-content\/uploads\/2022\/06\/centralita_movil_header-e1654679073280.png","width":1920,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/enreach.es\/en\/mobile\/virtual-pbx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/enreach.es\/en\/"},{"@type":"ListItem","position":2,"name":"MOBILE","item":"https:\/\/enreach.es\/en\/mobile\/"},{"@type":"ListItem","position":3,"name":"Mobile PBX"}]},{"@type":"WebSite","@id":"https:\/\/enreach.es\/#website","url":"https:\/\/enreach.es\/","name":"Enreach ES","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enreach.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/enreach.es\/en\/wp-json\/wp\/v2\/pages\/35058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enreach.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/enreach.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/enreach.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enreach.es\/en\/wp-json\/wp\/v2\/comments?post=35058"}],"version-history":[{"count":9,"href":"https:\/\/enreach.es\/en\/wp-json\/wp\/v2\/pages\/35058\/revisions"}],"predecessor-version":[{"id":54858,"href":"https:\/\/enreach.es\/en\/wp-json\/wp\/v2\/pages\/35058\/revisions\/54858"}],"up":[{"embeddable":true,"href":"https:\/\/enreach.es\/en\/wp-json\/wp\/v2\/pages\/35052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enreach.es\/en\/wp-json\/wp\/v2\/media\/27171"}],"wp:attachment":[{"href":"https:\/\/enreach.es\/en\/wp-json\/wp\/v2\/media?parent=35058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}